{"id":50200,"date":"2022-10-28T01:01:42","date_gmt":"2022-10-27T23:01:42","guid":{"rendered":"https:\/\/pharma-trend.com\/en\/taro-provides-results-for-september-30-2022\/"},"modified":"2022-10-28T01:01:42","modified_gmt":"2022-10-27T23:01:42","slug":"taro-provides-results-for-september-30-2022","status":"publish","type":"post","link":"https:\/\/pharma-trend.com\/en\/taro-provides-results-for-september-30-2022\/","title":{"rendered":"Taro Provides Results for September 30, 2022"},"content":{"rendered":"<div>\n<p>HAWTHORNE, N.Y.&#8211;(BUSINESS WIRE)&#8211;Taro Pharmaceutical Industries Ltd. (NYSE: TARO) (\u201cTaro\u201d or the \u201cCompany\u201d) today provided unaudited financial results for the quarter and six months ended September 30, 2022.\n<\/p>\n<p>\n<b>Quarter ended September 30, 2022* Highlights \u2500 compared to September 30, 2021<\/b>\n<\/p>\n<ul class=\"bwlistdisc\">\n<li>\nNet sales of $130.5 million decreased, principally due to the continued price decline particularly in the U.S. generic business, as well as a one-time gross-to-net (\u201cGTN\u201d) adjustment.\n<\/li>\n<li>\nGross profit of $47.0 million (36.0% of net sales) compared to $62.0 million (47.0% of net sales).\n<\/li>\n<li>\nResearch and development (R&amp;D) expenses of $11.5 million decreased slightly.\n<\/li>\n<li>\nSelling, marketing, general and administrative expenses (SG&amp;A) of $42.3 million increased $18.6 million.\n<\/li>\n<li>\nOperating loss of $(6.8) million compared to operating income of $24.4 million. The current year quarter operating loss is primarily attributable to the aforementioned price erosion and GTN adjustment, as well as the on-going impact associated with the integration of our recent acquisition.\n<\/li>\n<li>\nInterest and other financial income of $4.3 million increased $1.9 million.\n<\/li>\n<li>\nTax benefit of $2.1 million compared to tax expense of $6.1 million in the prior year quarter.\n<\/li>\n<li>\nNet loss attributable to Taro was $(2.8) million compared to net income of $23.3 million, resulting in (loss) per share of $(0.07) compared to earnings per share of $0.62. Excluding the impact from the settlement and loss contingencies charges in the prior year quarter, net income was $24.7 million, resulting in earnings per share of $0.66.\n<\/li>\n<\/ul>\n<p>\n<b>Six Months ended September 30, 2022* Highlights \u2500 compared to September 30, 2021<\/b>\n<\/p>\n<ul class=\"bwlistdisc\">\n<li>\nNet sales of $287.2 million increased $8.1 million.\n<\/li>\n<li>\nGross profit of $128.6 million (44.8% of net sales compared to 50.1%) decreased $11.2 million.\n<\/li>\n<li>\nR&amp;D expenses of $23.0 million decreased $2.4 million.\n<\/li>\n<li>\nSG&amp;A of $98.4 million increased $50.7 million.\n<\/li>\n<li>\nOperating income of $7.2 million compared to $5.2 million, Excluding the impact from the settlement and loss contingencies charges in the prior year, operating income was $66.6 million. The current year operating income primarily reflects the six-month impact of the factors mentioned above.\n<\/li>\n<li>\nInterest and other financial income of $6.2 million increased from $5.4 million.\n<\/li>\n<li>\nNet income attributable to Taro was $11.3 million compared to $4.6 million, resulting in earnings per share of $0.30 compared to earnings per share of $0.12. Excluding the impact from the settlement and loss contingencies charges in the prior year, net income was $66.0 million, resulting in diluted earnings per share of $1.75.\n<\/li>\n<\/ul>\n<p>\n<b>Cash Flow and Balance Sheet Highlights<\/b>\n<\/p>\n<ul class=\"bwlistdisc\">\n<li>\nCash flow used in operations for the six months ended September 30, 2022 was $37.7 million compared to $8.0 million for the six months ended September 30, 2021. Excluding the impact from the settlement and loss contingencies charges in both periods, cash flow provided by operations was $30.0 million compared to $94.9 million for the six months ended September 30, 2021.\n<\/li>\n<li>\nAs of September 30, 2022, cash and cash equivalents, short-term bank deposits and marketable securities (both short- and long-term) decreased $58.9 million to $1.2 billion from March 31, 2022; principally the result of a $67.6 million settlement payment to the Direct Purchaser Plaintiff (\u201cDPP\u201d) class in the In re: Generic Pharmaceuticals Pricing Antitrust Litigation, MDL No. 2724.\n<\/li>\n<\/ul>\n<p>\n<b>* The September 30, 2022 results include six months\u2019 results from the February 28<sup>th<\/sup> acquisition of Alchemee.<\/b>\n<\/p>\n<p>\n<b><span class=\"bwuline\">FDA Approvals and Filings<\/span><\/b>\n<\/p>\n<p>\nThe Company currently has a total of nineteen ANDAs awaiting FDA approval, including three tentative approvals.\n<\/p>\n<p>\nThe Company cautions that the foregoing 2022 financial information (including Alchemee) is unaudited and is subject to change.\n<\/p>\n<p class=\"bwalignc\">\n<b>************************<\/b>\n<\/p>\n<p>\n<b>About Taro<br \/>\n<br \/><\/b>Taro Pharmaceutical Industries Ltd. is a multinational, science-based pharmaceutical company dedicated to meeting the needs of its customers through the discovery, development, manufacturing and marketing of the highest quality healthcare products. For further information on Taro Pharmaceutical Industries Ltd., please visit the Company\u2019s website at <a target=\"_blank\" href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=http%3A%2F%2Fwww.taro.com&amp;esheet=52954950&amp;newsitemid=20221027006161&amp;lan=en-US&amp;anchor=www.taro.com&amp;index=1&amp;md5=d8f269eaa5589309f425724505e95e35\" rel=\"nofollow noopener\" shape=\"rect\">www.taro.com<\/a>.\n<\/p>\n<p>\n<b>SAFE HARBOR STATEMENT<br \/>\n<br \/><\/b><i>The unaudited consolidated financial statements have been prepared on the same basis as the annual consolidated financial statements and, in the opinion of management, reflect all adjustments necessary to present fairly the financial condition and results of operations of the Company. The unaudited consolidated financial statements should be read in conjunction with the Company\u2019s audited consolidated financial statements included in the Company\u2019s Annual Report on Form 20-F, as filed with the SEC.<\/i>\n<\/p>\n<p>\n<i>Certain statements in this release are forward-looking statements within the meaning of the Private Securities Litigation Reform Act of 1995. These statements include, but are not limited to, statements that do not describe historical facts or that refer or relate to events or circumstances the Company \u201cestimates,\u201d \u201cbelieves,\u201d or \u201cexpects\u201d to happen or similar language, and statements with respect to the Company\u2019s financial performance, availability of financial information, and estimates of financial results and information for fiscal year 2023. Although the Company believes the expectations reflected in such forward-looking statements to be based on reasonable assumptions, it can give no assurances that its expectations will be attained. Factors that could cause actual results to differ include general domestic and international economic conditions, industry and market conditions, changes in the Company&#8217;s financial position, litigation brought by any party in any court in Israel, the United States, or any country in which Taro operates, regulatory and legislative actions in the countries in which Taro operates, and other risks detailed from time to time in the Company\u2019s SEC reports, including its Annual Reports on Form 20-F. Forward-looking statements are applicable only as of the date on which they are made. The Company undertakes no obligations to update, change or revise any forward-looking statement, whether as a result of new information, additional or subsequent developments or otherwise.<\/i>\n<\/p>\n<p class=\"bwalignc\">\n<b><i>**Financial Tables Follow**<\/i><\/b>\n<\/p>\n<table cellspacing=\"0\" class=\"bwtablemarginb bwblockalignl bwwidth100\">\n<tr>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"17\" rowspan=\"1\"><b>TARO PHARMACEUTICAL INDUSTRIES LTD.<\/b><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"17\" rowspan=\"1\"><b>SUMMARY CONSOLIDATED STATEMENTS OF OPERATIONS<\/b><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"17\" rowspan=\"1\">(Unaudited)<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"17\" rowspan=\"1\">(U.S. dollars in thousands, except share data)<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"7\" rowspan=\"1\"><b>Quarter Ended<\/b><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"7\" rowspan=\"1\"><b>Six Months Ended<\/b><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignc bwvertalignm bwsinglebottom bwpadl0\" colspan=\"7\" rowspan=\"1\"><b>September 30,<\/b><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwsinglebottom bwpadl0\" colspan=\"7\" rowspan=\"1\"><b>September 30,<\/b><\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignc bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2022<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2021<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2022<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2021<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\"><b>Sales, net<\/b><\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>$<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>130,498<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>$<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>131,986<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>$<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>287,163<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>$<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>279,099<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\">Cost of sales<\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n83,536\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n69,941\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n158,595\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n139,356\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\"><b>Gross profit<\/b><\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>46,962<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>62,045<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>128,568<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>139,743<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\"><i>Operating Expenses:<\/i><\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl2 bwwidth56\" colspan=\"1\" rowspan=\"1\">Research and development<\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n11,522\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n12,495\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n23,030\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n25,448\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl2 bwwidth56\" colspan=\"1\" rowspan=\"1\">Selling, marketing, general and administrative<\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n42,255\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n23,684\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n98,377\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n47,660\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl2 bwwidth56\" colspan=\"1\" rowspan=\"1\">Settlements and loss contingencies<\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,420\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n61,420\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\"><b>Operating (loss) income *<\/b><\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>(6,815<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n<b>)<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>24,446<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>7,161<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>5,215<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\"><i>Financial (income) expense, net:<\/i><\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl2 bwwidth56\" colspan=\"1\" rowspan=\"1\">Interest and other financial income<\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(4,296\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(2,371\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(6,222\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(5,413\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl2 bwwidth56\" colspan=\"1\" rowspan=\"1\">Foreign exchange (income) expense<\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,788\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(264\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n3,082\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n11\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\">Other gain, net<\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n395\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,340\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n839\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,724\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\">Income (loss) before income taxes<\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(4,913\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n29,421\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n11,140\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n13,341\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\">Tax (benefit) expense<\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(2,100\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n6,104\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(126\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n8,792\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\"><b>Net (loss) income attributable to Taro *<\/b><\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>$<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>(2,813<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n<b>)<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>$<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>23,317<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>$<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>11,266<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>$<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>4,549<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\"><b>Net (loss) income per ordinary share attributable to Taro:<\/b><\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\">Basic and Diluted *<\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(0.07\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n0.62\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n0.30\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n0.12\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\"><b>Weighted-average number of shares used to compute net (loss) income per share:<\/b><\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\">Basic and Diluted<\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n37,584,891\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n37,600,580\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n37,584,891\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth8\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n37,696,975\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth1\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth56\" colspan=\"1\" rowspan=\"1\">May not foot due to rounding.<\/td>\n<td class=\"bwwidth1\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<\/table>\n<p>\n<i>Note: <\/i>Quarter and six months ended September 30, 2022 includes results from Alchemee (acquired February 28, 2022).\n<\/p>\n<p>\n<i>* Excluding the settlement and loss contingencies charges of $1.4 million for the quarter ended September 30, 2021, Operating income was $25.9 million, Net income attributable to Taro was $24.7 million, and basic and diluted earnings per share was $0.66.<\/i>\n<\/p>\n<p>\n<i>Excluding the settlement and loss contingencies charges of $61.4 million for the six months ended September 30, 2021, Operating income was $66.6 million, Net income attributable to Taro was $66.0 million, and basic and diluted earnings per share was $1.75.<\/i>\n<\/p>\n<table cellspacing=\"0\" class=\"bwtablemarginb bwblockalignl bwwidth100\">\n<tr>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"7\" rowspan=\"1\"><b>TARO PHARMACEUTICAL INDUSTRIES LTD.<\/b><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"7\" rowspan=\"1\"><b>SUMMARY CONSOLIDATED BALANCE SHEETS<\/b><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"7\" rowspan=\"1\">(U.S. dollars in thousands)<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"2\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"2\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0\" colspan=\"2\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n<b>September 30,<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0\" colspan=\"2\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n<b>March 31,<\/b>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwwidth3\" colspan=\"2\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2022<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwwidth3\" colspan=\"2\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2022<\/b>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\"><b>ASSETS<\/b><\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignt bwpadl0\" colspan=\"2\" rowspan=\"1\">(unaudited)<\/td>\n<td class=\"bwalignc bwvertalignt bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignt bwpadl0\" colspan=\"2\" rowspan=\"1\">(audited)<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\">CURRENT ASSETS:<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"2\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"2\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\">Cash and cash equivalents<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n175,191\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n251,134\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\">Short-term bank deposits<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n95,630\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n47,586\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\">Marketable securities<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n568,671\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n522,028\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\">Accounts receivable and other:<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"2\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"2\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl2 bwwidth64\" colspan=\"1\" rowspan=\"1\">Trade, net<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n248,495\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n246,972\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl2 bwwidth64\" colspan=\"1\" rowspan=\"1\">Other receivables and prepaid expenses<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n53,097\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n59,727\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\">Inventories<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n215,524\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n210,439\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\"><b>TOTAL CURRENT ASSETS<\/b><\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>1,356,608<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>1,337,886<\/b>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\">Marketable securities<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n357,586\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n435,189\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\">Property, plant and equipment, net<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n191,489\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n199,692\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\">Deferred income taxes<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n124,167\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n124,882\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\">Goodwill<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n12,718\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n11,820\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\">Other assets<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n64,711\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n66,893\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\"><b>TOTAL ASSETS<\/b><\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>$<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>2,107,279<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>$<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>2,176,362<\/b>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"2\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"2\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\"><b>LIABILITIES AND SHAREHOLDERS&#8217; EQUITY<\/b><\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"2\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"2\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\">CURRENT LIABILITIES:<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"2\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"2\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\">Trade payables<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n61,356\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n68,232\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\">Other current liabilities<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n313,495\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n363,886\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\"><b>TOTAL CURRENT LIABILITIES<\/b><\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>374,851<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>432,118<\/b>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\">Deferred taxes and other long-term liabilities<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n26,148\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n32,799\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\"><b>TOTAL LIABILITIES<\/b><\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>400,999<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>464,917<\/b>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"2\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"2\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\">Taro shareholders&#8217; equity<\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,706,280\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,711,445\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\"><b>TOTAL LIABILITIES AND SHAREHOLDERS&#8217; EQUITY<\/b><\/td>\n<td class=\"bwalignl bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>$<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>2,107,279<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth3\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>$<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth14\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>2,176,362<\/b>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0\" colspan=\"2\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0\" colspan=\"2\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0 bwwidth64\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"2\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignb bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"2\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<\/table>\n<p>\n<i>Note:<\/i> September 30, 2022, includes the Balance Sheet of Alchemee (acquired February 28, 2022).\n<\/p>\n<p>\n\u00a0\n<\/p>\n<table cellspacing=\"0\" class=\"bwtablemarginb bwblockalignl bwwidth100\">\n<tr>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"9\" rowspan=\"1\"><b>TARO PHARMACEUTICAL INDUSTRIES LTD.<\/b><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"9\" rowspan=\"1\"><b>SUMMARY CONSOLIDATED STATEMENTS OF CASH FLOWS<\/b><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"9\" rowspan=\"1\">(U.S. dollars in thousands)<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwsinglebottom bwpadl0\" colspan=\"7\" rowspan=\"1\"><b>Six Months Ended September 30,<\/b><\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2022<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2021<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwalignc\" colspan=\"3\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n(unaudited)\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwalignc\" colspan=\"3\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n\u00a0(unaudited)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><b>Cash flows from operating activities:<\/b><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><b>Net income (loss)<\/b><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>$<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>11,266<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>$<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>4,549<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><b><i>Adjustments required to reconcile net income (loss) to net cash used in operating activities:<\/i><\/b><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl2 bwwidth77\" colspan=\"1\" rowspan=\"1\">Depreciation and amortization<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n13,994\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n12,795\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl2 bwwidth77\" colspan=\"1\" rowspan=\"1\">Realized loss on sale of long-lived assets<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n551\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl2 bwwidth77\" colspan=\"1\" rowspan=\"1\">Change in derivative instruments, net<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(24\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(314\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl2 bwwidth77\" colspan=\"1\" rowspan=\"1\">Effect of change in exchange rate on marketable securities and bank deposits<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,358\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n404\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl2 bwwidth77\" colspan=\"1\" rowspan=\"1\">Deferred income taxes, net<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,245\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n16,927\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl2 bwwidth77\" colspan=\"1\" rowspan=\"1\">Increase (decrease) in trade receivables, net<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(2,071\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n16,868\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl2 bwwidth77\" colspan=\"1\" rowspan=\"1\">Increase in inventories, net<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(5,316\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(2,636\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl2\" colspan=\"2\" rowspan=\"1\">Decrease (increase) in other receivables, income tax receivables, prepaid expenses and other<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,739\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(2,472\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl2 bwwidth77\" colspan=\"1\" rowspan=\"1\">Decrease in trade, income tax, accrued expenses and other payables<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(71,798\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(59,982\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl2 bwwidth77\" colspan=\"1\" rowspan=\"1\">Expense from amortization of marketable securities bonds, net<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n6,940\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,287\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><b>Net cash used in operating activities<\/b><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>(37,667<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n<b>)<\/b>\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>(8,023<\/b>\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n<b>)<\/b>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><b>Cash flows from investing activities:<\/b><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl2 bwwidth77\" colspan=\"1\" rowspan=\"1\">Purchase of plant, property &amp; equipment, net<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(3,443\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(5,831\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl2 bwwidth77\" colspan=\"1\" rowspan=\"1\">Investment in other intangible assets<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(68\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(107\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl2 bwwidth77\" colspan=\"1\" rowspan=\"1\">Investment in short-term bank deposits, net<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(48,044\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(35,573\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl2 bwwidth77\" colspan=\"1\" rowspan=\"1\">Proceeds from (investment in) marketable securities, net<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n15,516\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(6,442\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><b>Net cash used in investing activities<\/b><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>(36,039<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n<b>)<\/b>\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>(47,953<\/b>\n<\/p>\n<\/td>\n<td class=\"bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n<b>)<\/b>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><b>Cash flows from financing activities:<\/b><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl2 bwwidth77\" colspan=\"1\" rowspan=\"1\">Purchase of treasury stock<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(24,934\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><b>Net cash used in financing activities<\/b><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>\u2014<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>(24,934<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n<b>)<\/b>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><b>Effect of exchange rate changes on cash and cash equivalents<\/b><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(2,237\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(599\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><b>Decrease in cash and cash equivalents<\/b><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(75,943\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(81,509\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><b>Cash and cash equivalents at beginning of period<\/b><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n251,134\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n605,177\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><b>Cash and cash equivalents at end of period<\/b><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>$<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>175,191<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>$<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n<b>523,668<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><b>Cash Paid during the year for:<\/b><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\">Income taxes<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n3,091\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,532\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><b>Cash Received during the year for:<\/b><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\">Income taxes<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n14,156\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,351\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><b>Non-cash investing transactions:<\/b><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\">Purchase of property, plant and equipment included in accounts payable<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n3,206\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n702\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><b>Non-cash financing transactions:<\/b><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\">Purchase of marketable securities, net<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n6,199\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth7\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n630\n<\/p>\n<\/td>\n<td class=\"bwalignr bwsinglebottom bwpadl0 bwpadr0 bwvertalignb bwwidth2\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignm bwpadl0 bwwidth77\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0 bwwidth1\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"3\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<\/table>\n<p>\n<i>Note:<\/i> September 30, 2022, includes the Balance Sheet of Alchemee (acquired February 28, 2022).\n<\/p>\n<p> <b>Contacts<\/b> <\/p>\n<p>\n<b>William J. Coote<\/b><br \/>VP, CFO<br \/>\n<br \/>(914) 345-9001<br \/>\n<br \/><a target=\"_blank\" href=\"&#109;&#x61;&#105;&#x6c;&#116;&#x6f;:&#x57;i&#x6c;l&#105;&#x61;&#109;&#x2e;&#67;&#x6f;&#111;&#x74;e&#x40;t&#x61;r&#111;&#x2e;&#99;&#x6f;&#109;\" rel=\"nofollow noopener\" shape=\"rect\">&#x57;&#105;l&#x6c;&#x69;&#97;m&#x2e;&#67;o&#x6f;&#x74;&#101;&#64;&#x74;&#97;r&#x6f;&#x2e;&#99;o&#x6d;<\/a>\n<\/p>\n<p>\n\u00a0\n<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>HAWTHORNE, N.Y.&#8211;(BUSINESS WIRE)&#8211;Taro Pharmaceutical Industries Ltd. (NYSE: TARO) (\u201cTaro\u201d or the \u201cCompany\u201d) today provided unaudited financial results for the quarter and six months ended September 30, 2022. Quarter ended September 30, 2022* Highlights \u2500 compared to September 30, 2021 Net sales of $130.5 million decreased, principally due to the continued price decline particularly in the &#8230; <span class=\"more\"><a class=\"more-link\" href=\"https:\/\/pharma-trend.com\/en\/taro-provides-results-for-september-30-2022\/\">[Read more&#8230;]<\/a><\/span><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":{"0":"entry","1":"post","2":"publish","3":"author-business","4":"post-50200","6":"format-standard","7":"category-industry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Taro Provides Results for September 30, 2022 - Pharma Trend<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pharma-trend.com\/en\/taro-provides-results-for-september-30-2022\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Taro Provides Results for September 30, 2022 - Pharma Trend\" \/>\n<meta property=\"og:description\" content=\"HAWTHORNE, N.Y.&#8211;(BUSINESS WIRE)&#8211;Taro Pharmaceutical Industries Ltd. (NYSE: TARO) (\u201cTaro\u201d or the \u201cCompany\u201d) today provided unaudited financial results for the quarter and six months ended September 30, 2022. Quarter ended September 30, 2022* Highlights \u2500 compared to September 30, 2021 Net sales of $130.5 million decreased, principally due to the continued price decline particularly in the ... [Read more...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pharma-trend.com\/en\/taro-provides-results-for-september-30-2022\/\" \/>\n<meta property=\"og:site_name\" content=\"Pharma Trend\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-27T23:01:42+00:00\" \/>\n<meta name=\"author\" content=\"Business Wire\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Business Wire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/taro-provides-results-for-september-30-2022\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/taro-provides-results-for-september-30-2022\\\/\"},\"author\":{\"name\":\"Business Wire\",\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/#\\\/schema\\\/person\\\/02d41342c7a74fa7f0032bb35ef0bb24\"},\"headline\":\"Taro Provides Results for September 30, 2022\",\"datePublished\":\"2022-10-27T23:01:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/taro-provides-results-for-september-30-2022\\\/\"},\"wordCount\":1421,\"publisher\":{\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/#organization\"},\"articleSection\":[\"Industry\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/taro-provides-results-for-september-30-2022\\\/\",\"url\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/taro-provides-results-for-september-30-2022\\\/\",\"name\":\"Taro Provides Results for September 30, 2022 - Pharma Trend\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/#website\"},\"datePublished\":\"2022-10-27T23:01:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/taro-provides-results-for-september-30-2022\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pharma-trend.com\\\/en\\\/taro-provides-results-for-september-30-2022\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/taro-provides-results-for-september-30-2022\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Taro Provides Results for September 30, 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/\",\"name\":\"Pharma Trend\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/#organization\",\"name\":\"Pharma Trend\",\"url\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Pharma Trend\"},\"image\":{\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/#\\\/schema\\\/person\\\/02d41342c7a74fa7f0032bb35ef0bb24\",\"name\":\"Business Wire\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Taro Provides Results for September 30, 2022 - Pharma Trend","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pharma-trend.com\/en\/taro-provides-results-for-september-30-2022\/","og_locale":"en_US","og_type":"article","og_title":"Taro Provides Results for September 30, 2022 - Pharma Trend","og_description":"HAWTHORNE, N.Y.&#8211;(BUSINESS WIRE)&#8211;Taro Pharmaceutical Industries Ltd. (NYSE: TARO) (\u201cTaro\u201d or the \u201cCompany\u201d) today provided unaudited financial results for the quarter and six months ended September 30, 2022. Quarter ended September 30, 2022* Highlights \u2500 compared to September 30, 2021 Net sales of $130.5 million decreased, principally due to the continued price decline particularly in the ... [Read more...]","og_url":"https:\/\/pharma-trend.com\/en\/taro-provides-results-for-september-30-2022\/","og_site_name":"Pharma Trend","article_published_time":"2022-10-27T23:01:42+00:00","author":"Business Wire","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Business Wire","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pharma-trend.com\/en\/taro-provides-results-for-september-30-2022\/#article","isPartOf":{"@id":"https:\/\/pharma-trend.com\/en\/taro-provides-results-for-september-30-2022\/"},"author":{"name":"Business Wire","@id":"https:\/\/pharma-trend.com\/en\/#\/schema\/person\/02d41342c7a74fa7f0032bb35ef0bb24"},"headline":"Taro Provides Results for September 30, 2022","datePublished":"2022-10-27T23:01:42+00:00","mainEntityOfPage":{"@id":"https:\/\/pharma-trend.com\/en\/taro-provides-results-for-september-30-2022\/"},"wordCount":1421,"publisher":{"@id":"https:\/\/pharma-trend.com\/en\/#organization"},"articleSection":["Industry"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/pharma-trend.com\/en\/taro-provides-results-for-september-30-2022\/","url":"https:\/\/pharma-trend.com\/en\/taro-provides-results-for-september-30-2022\/","name":"Taro Provides Results for September 30, 2022 - Pharma Trend","isPartOf":{"@id":"https:\/\/pharma-trend.com\/en\/#website"},"datePublished":"2022-10-27T23:01:42+00:00","breadcrumb":{"@id":"https:\/\/pharma-trend.com\/en\/taro-provides-results-for-september-30-2022\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pharma-trend.com\/en\/taro-provides-results-for-september-30-2022\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pharma-trend.com\/en\/taro-provides-results-for-september-30-2022\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/pharma-trend.com\/en\/"},{"@type":"ListItem","position":2,"name":"Taro Provides Results for September 30, 2022"}]},{"@type":"WebSite","@id":"https:\/\/pharma-trend.com\/en\/#website","url":"https:\/\/pharma-trend.com\/en\/","name":"Pharma Trend","description":"","publisher":{"@id":"https:\/\/pharma-trend.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pharma-trend.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/pharma-trend.com\/en\/#organization","name":"Pharma Trend","url":"https:\/\/pharma-trend.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pharma-trend.com\/en\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Pharma Trend"},"image":{"@id":"https:\/\/pharma-trend.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/pharma-trend.com\/en\/#\/schema\/person\/02d41342c7a74fa7f0032bb35ef0bb24","name":"Business Wire"}]}},"_links":{"self":[{"href":"https:\/\/pharma-trend.com\/en\/wp-json\/wp\/v2\/posts\/50200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pharma-trend.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pharma-trend.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pharma-trend.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pharma-trend.com\/en\/wp-json\/wp\/v2\/comments?post=50200"}],"version-history":[{"count":0,"href":"https:\/\/pharma-trend.com\/en\/wp-json\/wp\/v2\/posts\/50200\/revisions"}],"wp:attachment":[{"href":"https:\/\/pharma-trend.com\/en\/wp-json\/wp\/v2\/media?parent=50200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pharma-trend.com\/en\/wp-json\/wp\/v2\/categories?post=50200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pharma-trend.com\/en\/wp-json\/wp\/v2\/tags?post=50200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}