{"id":55282,"date":"2023-03-28T23:05:36","date_gmt":"2023-03-28T21:05:36","guid":{"rendered":"https:\/\/pharma-trend.com\/en\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\/"},"modified":"2023-03-28T23:05:36","modified_gmt":"2023-03-28T21:05:36","slug":"biote-reports-fourth-quarter-and-full-year-2022-financial-results","status":"publish","type":"post","link":"https:\/\/pharma-trend.com\/en\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\/","title":{"rendered":"Biote Reports Fourth Quarter and Full Year 2022 Financial Results"},"content":{"rendered":"<div>\n<p class=\"bwalignc\">\n<b>Achieved Full Year 2022 Record Revenue and Adjusted EBITDA for Full Year 2022<\/b>\n<\/p>\n<p class=\"bwalignc\">\n<b>Expect 2023 Revenue of $190-200 million and Adjusted EBITDA of $56-60 million<\/b>\n<\/p>\n<p class=\"bwalignc\">\n<b>Significantly Increased Trading Liquidity with Recent Successful Secondary Offering<\/b>\n<\/p>\n<p>IRVING, Texas&#8211;(BUSINESS WIRE)&#8211;<a target=\"_blank\" href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=https%3A%2F%2Fbiote.com%2F&amp;esheet=53369837&amp;newsitemid=20230328005857&amp;lan=en-US&amp;anchor=Biote&amp;index=1&amp;md5=bd03b6b5d1f76c566a862b2f10e8b240\" rel=\"nofollow noopener\" shape=\"rect\">Biote<\/a> (NASDAQ: BTMD), a leading solutions provider in preventive health care through the delivery of personalized hormone therapy, today announced financial results for the fourth quarter and full year ended December 31, 2022.\n<\/p>\n<p>\n<b><span class=\"bwuline\">Fourth Quarter Highlights, year over year<\/span>:<\/b>\n<\/p>\n<ul class=\"bwlistdisc\">\n<li>\nRevenue of $44.5 million, an 18.5% increase.\n<\/li>\n<li>\nNet income of $12.8 million and fully diluted GAAP earnings per share of $0.18.\n<\/li>\n<li>\nAdjusted EBITDA of $13.1 million, a 40% increase.<sup>1<\/sup>\n<\/li>\n<\/ul>\n<p>\n<b><span class=\"bwuline\">Full Year 2022 Highlights, year over year:<\/span><\/b>\n<\/p>\n<ul class=\"bwlistdisc\">\n<li>\nRevenue of $165.0 million, an 18.3% increase.\n<\/li>\n<li>\nNet income of $1.3 million and fully diluted GAAP loss per share of $(0.12).\n<\/li>\n<li>\nAdjusted EBITDA of $50.1 million, up 24.6%.<sup>2<\/sup>\n<\/li>\n<li>\nContinued to execute growth strategy to capture large market opportunity for both providers and patients\n<\/li>\n<\/ul>\n<p>\n\u201c<!-- no quote -->Biote achieved record financial results in the fourth quarter and for the full 2022 year, driven by strong growth in revenue and Adjusted EBITDA, which were at the high end of our guidance,\u201d said Biote Chief Executive Officer Terry Weber. \u201c<!-- no quote -->Our financial performance reflected successful execution of our growth strategy, as we further built our sales team and practitioner network in both existing and new geographic markets. Consumers increasingly seek treatment for many age-related symptoms often caused by hormonal imbalances, and the effectiveness of the Biote method continues to spur patient demand for the customized therapies offered by Biote-certified providers. As we strive to make the Biote brand synonymous with hormone replacement therapy, we remain dedicated to broadening public awareness by advancing the science and research supporting hormone optimization.\u201d\n<\/p>\n<p>\nMs. Weber continued, \u201c<!-- no quote -->In early January, we successfully completed a secondary offering of Biote Class A common stock, representing an important milestone in our journey as a public company. This transaction not only significantly increased the liquidity of our publicly traded shares, but also broadened institutional ownership of our shares. As a management team, we remain focused on building long-term shareholder value through profitable growth.\u201d\n<\/p>\n<p>\n<b>2022 Fourth Quarter Financial Review<\/b>\n<\/p>\n<p>\nRevenue for the fourth quarter of 2022 was $44.5 million, an increase of 18.5% from $37.5 million for the fourth quarter of 2021. The increase was driven by continued growth in both procedures and dietary supplements revenue, despite lingering weather-related impacts in Florida and Puerto Rico.\n<\/p>\n<p>\nGross profit margin for the fourth quarter of 2022 was 65.3% compared to 64.0% for the fourth quarter of 2021. The increase in gross profit margin was primarily due to effective cost management.\n<\/p>\n<p>\nOperating income for the fourth quarter of 2022 was $7.3 million, an increase of 23.3% from $5.9 million in the fourth quarter of 2021. The increase in operating income reflected increased profitability on higher sales, partially offset by higher SG&amp;A expense.\n<\/p>\n<p>\nNet income for the fourth quarter of 2022 was $12.8 million, or $0.18 per diluted share, compared to net income of $5.5 million for the fourth quarter of 2021. Net income increased due to the improvement in operating income and a favorable impact from transaction-related items, partially offset by increased interest expense. The net change in the fair value adjustments to warrant and earnout liabilities was $7.5 million in the fourth quarter, as compared to no such impact in the fourth quarter of 2021.\n<\/p>\n<p>\nAdjusted EBITDA for the fourth quarter of 2022 was $13.1 million compared to $9.4 million for the fourth quarter of 2021. The 40% increase in Adjusted EBITDA was driven by the growth in revenue as well as the positive leverage in our business model that enables profit to grow faster than revenue.<sup>3<\/sup>\n<\/p>\n<p>\n<b>2022 Full Year Financial Review<\/b>\n<\/p>\n<p>\nRevenue for 2022 was $165.0 million, an increase of 18.3% from $139.4 million in 2021. The increase was driven by continued growth in both procedures and dietary supplements revenue.\n<\/p>\n<p>\nGross profit margin for 2022 was 66.9% compared to 65.0% for 2021. The increase in gross profit margin was primarily due to a more favorable product mix.\n<\/p>\n<p>\nOperating loss for 2022 was $(60.7) million, compared to operating income of $34.6 million for 2021. Operating loss in 2022 reflected the impact of $21.6 million in transaction-related costs and $82.2 million in stock compensation expense. Excluding these costs, operating income would have been $43.1 million in 2022.\n<\/p>\n<p>\nNet income for 2022 was $1.3 million, or a loss of $0.12 per diluted share, compared to net income of $32.6 million in the fourth quarter of 2021.\n<\/p>\n<p>\nAdjusted EBITDA for 2022 was $50.1 million compared to $40.2 million for 2021. The 24.6% increase in Adjusted EBITDA was primarily driven by the growth in revenue and the positive operating leverage in our business model.<sup>4<\/sup>\n<\/p>\n<p>\n<b>2023 Financial Outlook<\/b>\n<\/p>\n<p>\n\u201c<!-- no quote -->Biote\u2019s annuity-like business model provides good visibility into our projected financial performance. In 2023 we anticipate continued growth in both revenue and Adjusted EBITDA, as we further build our market presence and practitioner network. We are investing to strengthen our infrastructure and capabilities while continuing to expand our sales team,\u201d said Ms. Weber.\n<\/p>\n<p>\n\u201c<!-- no quote -->Our 2023 financial forecast assumes stronger revenue growth and Adjusted EBITDA performance in the second half of the year as we begin to benefit from the contributions of sales personnel added at the end of last year,\u201d concluded Ms. Weber.\n<\/p>\n<table cellspacing=\"0\" class=\"bwtablemarginb bwblockalignc\">\n<tr>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\n<i>($ in millions)<\/i>\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwalignc\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n<b><span class=\"bwuline\">2023 Guidance Range<\/span><\/b>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwsinglebottom bwleftsingle bwrightsingle bwpadl0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\nRevenue\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrightsingle bwpadl0 bwalignc\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n$190-$200\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwsinglebottom bwleftsingle bwrightsingle bwpadl0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin\">\nAdjusted EBITDA\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrightsingle bwpadl0 bwalignc\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n$56-$60\n<\/p>\n<\/td>\n<\/tr>\n<\/table>\n<p>\n<b>Conference Call:<\/b>\n<\/p>\n<p>\nTerry Weber, Chief Executive Officer, and the Company\u2019s management will host a conference call to review these results and provide a business update beginning at 8:30 a.m. ET on Wednesday, March 29, 2023. To access the conference call by telephone, please dial (866) 524-3160 (U.S toll-free) or (412) 317-6760 (International). To access a live webcast of the call, interested parties may use the following link: <a target=\"_blank\" href=\"https:\/\/cts.businesswire.com\/ct\/CT?id=smartlink&amp;url=https%3A%2F%2Fevent.choruscall.com%2Fmediaframe%2Fwebcast.html%3Fwebcastid%3DkkrU5tBp&amp;esheet=53369837&amp;newsitemid=20230328005857&amp;lan=en-US&amp;anchor=Biote+Q4+and+Full+Year+2022+Earnings+Webcast&amp;index=2&amp;md5=4ebdf1eb592492781026cdcc532503bb\" rel=\"nofollow noopener\" shape=\"rect\">Biote Q4 and Full Year 2022 Earnings Webcast<\/a>. A replay of the webcast will be available on the Events page of the Biote Investor Relations website, at <i>ir.biote.com<\/i>, shortly after the event concludes.\n<\/p>\n<p>\n<b>Discussion of Non-GAAP Financial Measures<\/b>\n<\/p>\n<p>\nTo provide investors with additional information regarding our financial results, Biote has disclosed Adjusted EBITDA, a non-GAAP financial measure that it calculates as net income before interest, taxes and depreciation and amortization, further adjusted to exclude stock-based compensation, transaction-related expenses, fair value adjustments to certain equity instruments classified as liabilities and other non-operating costs. Below we have provided a reconciliation of net income (the most directly comparable GAAP financial measure) to Adjusted EBITDA.\n<\/p>\n<p>\nWe present Adjusted EBITDA because it is a key measure used by our management to evaluate our operating performance, generate future operating plans and determine payments under compensation programs. Accordingly, we believe that Adjusted EBITDA provides useful information to investors and others in understanding and evaluating our operating results in the same manner as our management.\n<\/p>\n<p>\nAdjusted EBITDA has limitations as an analytical tool, and you should not consider it in isolation or as a substitute for analysis of our results as reported under GAAP. Some of these limitations are as follows:\n<\/p>\n<ul class=\"bwlistdisc\">\n<li>\nAlthough depreciation and amortization are non-cash charges, the assets being depreciated and amortized may have to be replaced in the future, and Adjusted EBITDA does not reflect cash capital expenditure requirements for such replacements or for assets;\n<\/li>\n<li>\nAdjusted EBITDA does not reflect changes in, or cash requirements for, our working capital needs; and\n<\/li>\n<li>\nAdjusted EBITDA does not reflect tax payments that may represent a reduction in cash available to us.\n<\/li>\n<\/ul>\n<p>\nIn addition, Adjusted EBITDA is subject to inherent limitations as it reflects the exercise of judgment by Biote\u2019s management about which expenses are excluded or included. A reconciliation is provided in the financial statement tables included below in this press release for each non-GAAP financial measure to the most directly comparable financial measure stated in accordance with GAAP. Because of these limitations, you should consider Adjusted EBITDA alongside other financial performance measures, including net income and our other GAAP results.\n<\/p>\n<p>\n<b>About Biote<\/b>\n<\/p>\n<p>\nBiote is transforming healthy aging through innovative, personalized hormone optimization therapies delivered by Biote-certified medical providers. Biote trains practitioners how to identify and treat early indicators of hormone-related aging conditions, an underserved $7 billion global market, providing affordable symptom relief for patients and driving clinic success for practitioners.\n<\/p>\n<p>\n<b>Forward-Looking Statements<\/b>\n<\/p>\n<p>\nExcept for historical information contained herein, this press release contains certain forward-looking statements within the meaning of Section 27A of the Securities Act of 1933, as amended, and Section 21E of the Securities Exchange Act of 1934, as amended. Some of the forward-looking statements can be identified by the use of forward-looking words. Statements that are not historical in nature, including the words \u201cmay,\u201d \u201ccan,\u201d \u201cshould,\u201d \u201cwill,\u201d \u201cestimate,\u201d \u201cplan,\u201d \u201cproject,\u201d \u201cforecast,\u201d \u201cintend,\u201d \u201cexpect,\u201d \u201chope,\u201d \u201canticipate,\u201d \u201cbelieve,\u201d \u201cseek,\u201d \u201ctarget,\u201d \u201ccontinue,\u201d \u201ccould,\u201d \u201cmight,\u201d \u201congoing,\u201d \u201cpotential,\u201d \u201cpredict,\u201d \u201cwould\u201d and other similar expressions, are intended to identify forward-looking statements. Forward-looking statements are predictions, projections and other statements about future events that are based on current expectations and assumptions and, as a result, are subject to risks and uncertainties. Many factors could cause actual results or developments to differ materially from those expressed or implied by such forward-looking statements, including but not limited to: the success of our dietary supplements to attain significant market acceptance among clinics, practitioners and their patients; our customers\u2019 reliance on certain third parties to support the manufacturing of bio-identical hormones for prescribers; our and our customers\u2019 sensitive to regulatory, economic, environmental and competitive conditions in certain geographic regions; our ability to increase the use by practitioners and clinics of the Biote Method at the rate that we anticipate or at all; our ability to grow our business; the significant competition we face in our industry; our limited operating history; our ability to protect our intellectual property; the unpredictability of the effects of the COVID-19 pandemic; the heavy regulatory oversight in our industry; changes in applicable laws or regulations; the inability to profitably expand in existing markets and into new markets; the possibility that we may be adversely impacted by other economic, business and\/or competitive factors, including recent bank failures; and future exchange and interest rates. The foregoing list of factors is not exhaustive. You should carefully consider the foregoing factors and the other risks and uncertainties described in the \u201cRisk Factors\u201d section of Biote\u2019s Quarterly Report on Form 10-Q for the quarter ended September 30, 2022 and other documents filed by Biote from time to time with the Securities and Exchange Commission, including our Annual Report on Form 10-K for the year ended December 31, 2022. These filings identify and address other important risks and uncertainties that could cause actual events and results to differ materially from those contained in the forward-looking statements. Forward-looking statements speak only as of the date they are made. Readers are cautioned not to put undue reliance on forward-looking statements, and Biote assumes no obligation and does not intend to update or revise these forward-looking statements, whether as a result of new information, future events, or otherwise. Biote does not give any assurance that it will achieve its expectations.\n<\/p>\n<p>\n<b>Financial Tables<\/b>\n<\/p>\n<table cellspacing=\"0\" class=\"bwtablemarginb bwblockalignl\">\n<tr>\n<td class=\"bwpadl0\" colspan=\"9\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0 bwalignc\" colspan=\"9\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\nBiote Corp.<br \/>\n<br \/>Consolidated Balance Sheets<br \/>\n<br \/>(In Thousands)<br \/>\n<br \/>(Unaudited)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"3\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0 bwnowrap\" colspan=\"3\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n<b>December 31,<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0 bwnowrap\" colspan=\"3\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n<b>December 31,<\/b>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2022<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwalignc bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2021<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><b>Assets<\/b><\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\">Current assets:<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Cash<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n79,231\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n26,766\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Accounts receivable, net<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n6,948\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,231\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Inventory, net<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n11,183\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n9,615\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Other current assets<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n3,816\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,473\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl8\" colspan=\"1\" rowspan=\"1\">Total current assets<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n101,178\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n47,085\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\">Property and equipment, net<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,504\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,335\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Capitalized software, net<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,073\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,554\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\">Operating lease right-of-use assets<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,052\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n356\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Deferred tax asset<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,838\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl8\" colspan=\"1\" rowspan=\"1\">Total assets<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n111,645\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n54,330\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><b>Liabilities and Stockholders\u2019 Equity (Deficit)<\/b><\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Current liabilities:<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Accounts payable<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,112\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,349\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Accrued expenses<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n6,274\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n6,011\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Term loan, current<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n6,250\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,000\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Deferred revenue, current<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,965\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,705\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Operating lease liabilities, current<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n165\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n248\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl8\" colspan=\"1\" rowspan=\"1\">Total current liabilities<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n18,766\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n17,313\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\">Term loan, net of current portion<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n112,086\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n31,963\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Deferred revenue, net of current portion<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n926\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n802\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\">Operating lease liabilities, net of current portion<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,927\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n127\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Warrant liability<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,104\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\">Earnout liability<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n32,110\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl8\" colspan=\"1\" rowspan=\"1\">Total liabilities<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n169,919\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n50,205\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\">Commitments and contingencies (See Note 18)<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Stockholders\u2019 Equity (Deficit)<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Class A, AA, AAA, and AAAA units, no par value, unlimited units authorized; no and 1,013,197 units issued, no and 982,800 units outstanding as of December 31, 2022 and December 31, 2021, respectively<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Preferred stock, $0.0001 par value, 10,000,000 shares authorized; no shares issued or outstanding<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Class A common stock, $0.0001 par value, 600,000,000 shares authorized; 11,242,887 and no shares issued, 9,655,387 and no shares outstanding as of December 31, 2022 and December 31, 2021, respectively<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignt bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Class B common stock, $0.0001 par value, 8,000,000 shares authorized; no shares issued or outstanding as of December 31, 2022 and December 31, 2021<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Class V voting stock, $0.0001 par value, 100,000,000 shares authorized; 58,565,824 and no shares issued, 48,565,824 and no shares outstanding as of December 31, 2022 and December 31, 2021, respectively<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Additional paid-in capital<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Retained earnings (Accumulated deficit)<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(44,460\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,165\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Accumulated other comprehensive loss<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(5\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(40\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl8\" colspan=\"1\" rowspan=\"1\">biote Corp.\u2019s stockholders\u2019 equity (deficit)<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(44,459\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,125\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Noncontrolling interest<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(13,815\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl8\" colspan=\"1\" rowspan=\"1\">Total stockholders\u2019 equity (deficit)<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(58,274\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,125\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl8\" colspan=\"1\" rowspan=\"1\">Total liabilities and stockholders\u2019 equity (deficit)<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n111,645\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n54,330\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<\/table>\n<table cellspacing=\"0\" class=\"bwtablemarginb bwblockalignl\">\n<tr>\n<td class=\"bwpadl0 bwalignc\" colspan=\"17\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\nBiote Corp.<br \/>\n<br \/>Consolidated Statements of Operations<br \/>\n<br \/>(In Thousands, except per share values)<br \/>\n<br \/>(Unaudited)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"7\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"7\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwnowrap\" colspan=\"7\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n<b>Three Months Ended December 31,<\/b>\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwalignc bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwnowrap\" colspan=\"7\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n<b>Year Ended December 31,<\/b>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2022<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwalignc bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2021<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwalignc bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2022<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwalignc bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2021<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Revenue:<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignt bwpadl4\" colspan=\"1\" rowspan=\"1\">Product revenue<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n44,012\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignt bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n36,979\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n163,133\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignt bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n137,598\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignt bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Service revenue<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n473\n<\/p>\n<\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n557\n<\/p>\n<\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,824\n<\/p>\n<\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,798\n<\/p>\n<\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignt bwpadl8\" colspan=\"1\" rowspan=\"1\">Total revenue<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n44,485\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignt bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n37,536\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n164,957\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignt bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n139,396\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Cost of revenue (excluding depreciation and amortization included in selling, general and administrative, below)<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignt bwpadl4\" colspan=\"1\" rowspan=\"1\">Cost of products<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n14,599\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignt bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n12,802\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n51,990\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignt bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n46,298\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignt bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Cost of services<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n825\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n724\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,585\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,519\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl8\" colspan=\"1\" rowspan=\"1\">Cost of revenue<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n15,424\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n13,526\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n54,575\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n48,817\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Commissions<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n186\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n449\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n974\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,056\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\">Marketing<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,276\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,683\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,628\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,908\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Selling, general and administrative<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n20,296\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n15,953\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n165,502\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n49,054\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl8\" colspan=\"1\" rowspan=\"1\">Income (loss) from operations<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n7,303\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,925\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(60,722\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n34,561\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Other income (expense), net:<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Interest expense<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(2,182\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(372\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(5,091\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(1,673\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Gain from change in fair value of warrant liability<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n575\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,127\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Gain from change in fair value of earnout liability<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n6,930\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n61,770\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Loss from extinguishment of debt<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(445\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Other income<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n619\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,073\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n17\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl8\" colspan=\"1\" rowspan=\"1\">Total other income (expense), net<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,942\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(368\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n62,434\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(1,656\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl8\" colspan=\"1\" rowspan=\"1\">Income before provision for income taxes<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n13,245\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,557\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,712\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n32,905\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Income tax expense<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n436\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n77\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n388\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n286\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl8\" colspan=\"1\" rowspan=\"1\">Net income<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n12,809\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,480\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,324\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n32,619\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Less: Net income attributable to noncontrolling interest<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n11,187\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,293\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl8\" colspan=\"1\" rowspan=\"1\">Net income (loss) attributable to biote Corp. stockholders<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,622\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(969\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\">Other comprehensive income (loss):<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Foreign currency translation adjustments<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(1\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(3\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(1\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(17\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwsinglebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl8\" colspan=\"1\" rowspan=\"1\">Other comprehensive income (loss)<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(1\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(3\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(1\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(17\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl8\" colspan=\"1\" rowspan=\"1\">Comprehensive income<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n12,808\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,477\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,323\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n32,602\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Net income (loss) per common share<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Basic<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n0.19\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(0.12\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Diluted<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n0.18\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(0.12\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\">Weighted average common shares outstanding<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Basic<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n8,703,533\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n8,059,371\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Diluted<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n58,750,051\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n8,059,371\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"3\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<\/table>\n<table cellspacing=\"0\" class=\"bwtablemarginb bwblockalignl\">\n<tr>\n<td class=\"bwpadl0 bwalignc\" colspan=\"9\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\nBiote Corp.<br \/>\n<br \/>Consolidated Statements of Cash Flows<br \/>\n<br \/>(In Thousands)<br \/>\n<br \/>(Unaudited)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"7\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignc bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwnowrap\" colspan=\"7\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n<b>Year Ended December 31,<\/b>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignc bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2022<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2021<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignt bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><b>Operating Activities<\/b><\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignt bwpadl0\" colspan=\"1\" rowspan=\"1\">Net income<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,324\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n32,619\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Adjustments to reconcile net income to net cash (used in) provided by operating activities:<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Depreciation and amortization<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,199\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,400\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Bad debt expense (recoveries)<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(155\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n240\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Amortization of debt issuance costs<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n589\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n222\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Provision for obsolete inventory<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n140\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n471\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Non-cash lease expense<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n240\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n226\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Non-cash sponsor share transfers<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n7,216\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Non-cash fees under SEPA<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n119\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Share-based compensation expense<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n82,180\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Gain from change in fair value of warrant liability<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(5,127\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Gain from change in fair value of earnout liability<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(61,770\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Loss from extinguishment of debt<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n445\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Deferred income taxes<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(743\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignt bwpadl4\" colspan=\"1\" rowspan=\"1\">Changes in operating assets and liabilities:<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignt bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignl bwvertalignt bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignt bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl8\" colspan=\"1\" rowspan=\"1\">Accounts receivable<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(1,562\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(752\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl8\" colspan=\"1\" rowspan=\"1\">Inventory<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(1,708\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(5,762\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl8\" colspan=\"1\" rowspan=\"1\">Other current assets<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(2,284\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n34\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl8\" colspan=\"1\" rowspan=\"1\">Accounts payable<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n416\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,605\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl8\" colspan=\"1\" rowspan=\"1\">Deferred revenue<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n384\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(373\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl8\" colspan=\"1\" rowspan=\"1\">Accrued expenses<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(30,841\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,029\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl8\" colspan=\"1\" rowspan=\"1\">Operating lease liabilities<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(219\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(239\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignt bwpadl0\" colspan=\"1\" rowspan=\"1\">Net cash (used in) provided by operating activities<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(9,157\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignt bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n33,720\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><b>Investing Activities<\/b><\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Purchases of property and equipment<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(333\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(1,448\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Purchases of capitalized software<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(1,505\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(2,359\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\">Net cash used in investing activities<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(1,838\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(3,807\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><b>Financing Activities<\/b><\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Proceeds from the Business Combination<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n12,282\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Principal repayments on term loan<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(4,375\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(5,000\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Borrowings on term loan<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n125,000\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Extinguishment of Bank of America term loan<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(36,250\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Debt issuance costs<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(4,036\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Settlement of phantom equity rights<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(7,250\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Settlement of RSUs<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(424\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Distributions<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(12,886\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(11,402\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Capitalized transaction costs<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(8,341\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(3,941\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Proceeds from issuance of shares under SEPA<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n442\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">SEPA transaction costs<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(702\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Net cash provided by (used in) financing activities<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n63,460\n<\/p>\n<\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(20,343\n<\/p>\n<\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\">Effect of exchange rate changes on cash and cash equivalents<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(12\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Net increase in cash and cash equivalents<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n52,465\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n9,558\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\">Cash and cash equivalents at beginning of period<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n26,766\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n17,208\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwsinglebottom bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Cash and cash equivalents at end of period<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n79,231\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n26,766\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\">Supplemental Disclosure of Cash Flow Information<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Cash paid for interest<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,426\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,462\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Cash paid for income taxes<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n282\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n171\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Non-cash investing and financing activities<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwpadl4\" colspan=\"1\" rowspan=\"1\">Capital expenditures and capitalized software included in accounts payable<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n49\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n282\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Non-cash SEPA transaction costs<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n119\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignb bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwvertalignb bwrowaltcolor0 bwpadl0 bwpadr0\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<\/table>\n<table cellspacing=\"0\" class=\"bwtablemarginb bwblockalignl\">\n<tr>\n<td class=\"bwpadl0 bwalignc\" colspan=\"17\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\nBiote Corp.<br \/>\n<br \/>Reconciliation of Adjusted EBITDA to Net (Loss) Income<br \/>\n<br \/>(In Thousands)<br \/>\n<br \/>(Unaudited)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"7\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"7\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignc bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0 bwnowrap\" colspan=\"7\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n<b>Three Months Ended<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0 bwnowrap\" colspan=\"7\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n<b>Year Ended<\/b>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignc bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwnowrap\" colspan=\"7\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n<b>December 31,<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwnowrap\" colspan=\"7\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n<b>December 31,<\/b>\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignc bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2022<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2021<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2022<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwpadl0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignc bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n<b>2021<\/b>\n<\/p>\n<\/td>\n<td class=\"bwalignc bwvertalignb bwsinglebottom bwpadl0 bwpadr0 bwnowrap\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignc\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Net income<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n12,809\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,480\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,324\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n32,619\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl4\" colspan=\"1\" rowspan=\"1\">Interest expense<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,182\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n372\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n5,091\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,673\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Income tax expense<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n436\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n77\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n388\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n286\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl4\" colspan=\"1\" rowspan=\"1\">Depreciation and amortization<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n555\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n413\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,199\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,400\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Loss from extinguishment of debt and other non-operating items<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(619\n<\/p>\n<\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(4\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(628\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(17\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl4\" colspan=\"1\" rowspan=\"1\">Share-based compensation expense<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,164\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n82,180\n<\/p>\n<\/td>\n<td class=\"bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Transaction-related expenses<\/td>\n<td class=\"bwalignl bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n978\n<\/p>\n<\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,503\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignl bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n21,627\n<\/p>\n<\/td>\n<td class=\"bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,387\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl4\" colspan=\"1\" rowspan=\"1\">Litigation and other<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n2,118\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,531\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n4,843\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n1,869\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwrowaltcolor0 bwpadl4\" colspan=\"1\" rowspan=\"1\">Gain from change in fair value of warrant liability<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(575\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(5,127\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwalignr bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwpadl4\" colspan=\"1\" rowspan=\"1\">Gain from change in fair value of earnout liability<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(6,930\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n(61,770\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n)\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n\u2014\n<\/p>\n<\/td>\n<td class=\"bwalignr bwpadl0 bwsinglebottom bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwalignl bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\">Adjusted EBITDA<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n13,118\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n9,373\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n50,127\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<td class=\"bwvertalignm bwrowaltcolor0 bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwalignr bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n$\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwalignr bwcellpmargin\">\n40,218\n<\/p>\n<\/td>\n<td class=\"bwalignr bwdoublebottom bwrowaltcolor0 bwpadl0 bwpadr0 bwvertalignb\" colspan=\"1\" rowspan=\"1\">\n<p class=\"bwcellpmargin bwalignl\">\n\u00a0\n<\/p>\n<\/td>\n<\/tr>\n<tr>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"3\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"1\" rowspan=\"1\"><\/td>\n<td class=\"bwpadl0\" colspan=\"3\" rowspan=\"1\">\u00a0<\/td>\n<\/tr>\n<\/table>\n<p>\n_________________________\n<\/p>\n<p>\n<sup>1,2<\/sup> Please see the \u201cReconciliations of Adjusted EBITDA\u201d table below for a reconciliation of Adjusted EBITDA to the most directly comparable GAAP measure, net income, and additional information about Adjusted EBITDA.\n<\/p>\n<p>\n<sup>3<\/sup> Please see the \u201cReconciliations of Adjusted EBITDA\u201d table for a reconciliation of Adjusted EBITDA to the most directly comparable GAAP measure, net income, and additional information about Adjusted EBITDA.\n<\/p>\n<p>\n<sup>4<\/sup> Please see the \u201cReconciliations of Adjusted EBITDA\u201d table for a reconciliation of Adjusted EBITDA to the most directly comparable GAAP measure, net income, and additional information about Adjusted EBITDA.\n<\/p>\n<p> <b>Contacts<\/b> <\/p>\n<p>\n<b>Investor Relations:<\/b><br \/>Eric Prouty<br \/>\n<br \/>AdvisIRy Partners<br \/>\n<br \/><a target=\"_blank\" href=\"&#109;a&#x69;l&#x74;o&#x3a;&#101;&#x72;&#105;&#x63;&#46;p&#x72;o&#x75;t&#x79;&#64;&#x61;&#100;&#x76;&#105;&#x73;&#105;r&#x79;&#46;&#x63;o&#x6d;\" rel=\"nofollow noopener\" shape=\"rect\">&#101;&#114;&#x69;c&#46;&#x70;&#x72;o&#117;&#x74;&#x79;&#64;&#97;&#x64;&#x76;i&#115;&#x69;&#x72;y&#46;&#x63;&#x6f;m<\/a>\n<\/p>\n<p>\n<b>Media:<\/b><br \/><a target=\"_blank\" href=\"&#109;&#97;&#x69;l&#116;&#x6f;&#x3a;P&#114;&#x65;&#x73;s&#64;&#x62;i&#111;&#x74;&#x65;&#46;&#99;&#x6f;&#x6d;\" rel=\"nofollow noopener\" shape=\"rect\">P&#114;&#101;&#x73;&#x73;&#x40;&#x62;i&#111;&#116;&#101;&#x2e;&#x63;&#x6f;m<\/a>\n<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Achieved Full Year 2022 Record Revenue and Adjusted EBITDA for Full Year 2022 Expect 2023 Revenue of $190-200 million and Adjusted EBITDA of $56-60 million Significantly Increased Trading Liquidity with Recent Successful Secondary Offering IRVING, Texas&#8211;(BUSINESS WIRE)&#8211;Biote (NASDAQ: BTMD), a leading solutions provider in preventive health care through the delivery of personalized hormone therapy, today &#8230; <span class=\"more\"><a class=\"more-link\" href=\"https:\/\/pharma-trend.com\/en\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\/\">[Read more&#8230;]<\/a><\/span><\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[13],"tags":[],"class_list":{"0":"entry","1":"post","2":"publish","3":"author-business","4":"post-55282","6":"format-standard","7":"category-industry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Biote Reports Fourth Quarter and Full Year 2022 Financial Results - Pharma Trend<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/pharma-trend.com\/en\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Biote Reports Fourth Quarter and Full Year 2022 Financial Results - Pharma Trend\" \/>\n<meta property=\"og:description\" content=\"Achieved Full Year 2022 Record Revenue and Adjusted EBITDA for Full Year 2022 Expect 2023 Revenue of $190-200 million and Adjusted EBITDA of $56-60 million Significantly Increased Trading Liquidity with Recent Successful Secondary Offering IRVING, Texas&#8211;(BUSINESS WIRE)&#8211;Biote (NASDAQ: BTMD), a leading solutions provider in preventive health care through the delivery of personalized hormone therapy, today ... [Read more...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/pharma-trend.com\/en\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\/\" \/>\n<meta property=\"og:site_name\" content=\"Pharma Trend\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-28T21:05:36+00:00\" \/>\n<meta name=\"author\" content=\"Business Wire\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Business Wire\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\\\/\"},\"author\":{\"name\":\"Business Wire\",\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/#\\\/schema\\\/person\\\/02d41342c7a74fa7f0032bb35ef0bb24\"},\"headline\":\"Biote Reports Fourth Quarter and Full Year 2022 Financial Results\",\"datePublished\":\"2023-03-28T21:05:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\\\/\"},\"wordCount\":2559,\"publisher\":{\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/#organization\"},\"articleSection\":[\"Industry\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\\\/\",\"url\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\\\/\",\"name\":\"Biote Reports Fourth Quarter and Full Year 2022 Financial Results - Pharma Trend\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/#website\"},\"datePublished\":\"2023-03-28T21:05:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/pharma-trend.com\\\/en\\\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Biote Reports Fourth Quarter and Full Year 2022 Financial Results\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/\",\"name\":\"Pharma Trend\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/#organization\",\"name\":\"Pharma Trend\",\"url\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"\",\"contentUrl\":\"\",\"caption\":\"Pharma Trend\"},\"image\":{\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/pharma-trend.com\\\/en\\\/#\\\/schema\\\/person\\\/02d41342c7a74fa7f0032bb35ef0bb24\",\"name\":\"Business Wire\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Biote Reports Fourth Quarter and Full Year 2022 Financial Results - Pharma Trend","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/pharma-trend.com\/en\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\/","og_locale":"en_US","og_type":"article","og_title":"Biote Reports Fourth Quarter and Full Year 2022 Financial Results - Pharma Trend","og_description":"Achieved Full Year 2022 Record Revenue and Adjusted EBITDA for Full Year 2022 Expect 2023 Revenue of $190-200 million and Adjusted EBITDA of $56-60 million Significantly Increased Trading Liquidity with Recent Successful Secondary Offering IRVING, Texas&#8211;(BUSINESS WIRE)&#8211;Biote (NASDAQ: BTMD), a leading solutions provider in preventive health care through the delivery of personalized hormone therapy, today ... [Read more...]","og_url":"https:\/\/pharma-trend.com\/en\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\/","og_site_name":"Pharma Trend","article_published_time":"2023-03-28T21:05:36+00:00","author":"Business Wire","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Business Wire","Est. reading time":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/pharma-trend.com\/en\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\/#article","isPartOf":{"@id":"https:\/\/pharma-trend.com\/en\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\/"},"author":{"name":"Business Wire","@id":"https:\/\/pharma-trend.com\/en\/#\/schema\/person\/02d41342c7a74fa7f0032bb35ef0bb24"},"headline":"Biote Reports Fourth Quarter and Full Year 2022 Financial Results","datePublished":"2023-03-28T21:05:36+00:00","mainEntityOfPage":{"@id":"https:\/\/pharma-trend.com\/en\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\/"},"wordCount":2559,"publisher":{"@id":"https:\/\/pharma-trend.com\/en\/#organization"},"articleSection":["Industry"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/pharma-trend.com\/en\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\/","url":"https:\/\/pharma-trend.com\/en\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\/","name":"Biote Reports Fourth Quarter and Full Year 2022 Financial Results - Pharma Trend","isPartOf":{"@id":"https:\/\/pharma-trend.com\/en\/#website"},"datePublished":"2023-03-28T21:05:36+00:00","breadcrumb":{"@id":"https:\/\/pharma-trend.com\/en\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/pharma-trend.com\/en\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/pharma-trend.com\/en\/biote-reports-fourth-quarter-and-full-year-2022-financial-results\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/pharma-trend.com\/en\/"},{"@type":"ListItem","position":2,"name":"Biote Reports Fourth Quarter and Full Year 2022 Financial Results"}]},{"@type":"WebSite","@id":"https:\/\/pharma-trend.com\/en\/#website","url":"https:\/\/pharma-trend.com\/en\/","name":"Pharma Trend","description":"","publisher":{"@id":"https:\/\/pharma-trend.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/pharma-trend.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/pharma-trend.com\/en\/#organization","name":"Pharma Trend","url":"https:\/\/pharma-trend.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/pharma-trend.com\/en\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Pharma Trend"},"image":{"@id":"https:\/\/pharma-trend.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/pharma-trend.com\/en\/#\/schema\/person\/02d41342c7a74fa7f0032bb35ef0bb24","name":"Business Wire"}]}},"_links":{"self":[{"href":"https:\/\/pharma-trend.com\/en\/wp-json\/wp\/v2\/posts\/55282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pharma-trend.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pharma-trend.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pharma-trend.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/pharma-trend.com\/en\/wp-json\/wp\/v2\/comments?post=55282"}],"version-history":[{"count":0,"href":"https:\/\/pharma-trend.com\/en\/wp-json\/wp\/v2\/posts\/55282\/revisions"}],"wp:attachment":[{"href":"https:\/\/pharma-trend.com\/en\/wp-json\/wp\/v2\/media?parent=55282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pharma-trend.com\/en\/wp-json\/wp\/v2\/categories?post=55282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pharma-trend.com\/en\/wp-json\/wp\/v2\/tags?post=55282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}